{"id":9466,"date":"2021-09-30T22:52:43","date_gmt":"2021-09-30T20:52:43","guid":{"rendered":"https:\/\/mac.colleccions.cat\/objecte\/mac-ull-03484\/"},"modified":"2025-12-04T14:34:11","modified_gmt":"2025-12-04T13:34:11","slug":"mac-ull-03484","status":"publish","type":"objecte","link":"https:\/\/mac.colleccions.cat\/en\/objecte\/mac-ull-03484\/","title":{"rendered":"aplic en forma de cap"},"content":{"rendered":"","protected":false},"featured_media":9452,"template":"","meta":{"_acf_changed":false,"inline_featured_image":false},"museu":[75],"class_list":["post-9466","objecte","type-objecte","status-publish","has-post-thumbnail","hentry","museu-museu-darqueologia-de-catalunya-ullastret-en"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>aplic en forma de cap - MAC<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/mac.colleccions.cat\/en\/objecte\/mac-ull-03484\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"aplic en forma de cap - MAC\" \/>\n<meta property=\"og:description\" content=\"[...]Read More... from aplic en forma de cap\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mac.colleccions.cat\/en\/objecte\/mac-ull-03484\/\" \/>\n<meta property=\"og:site_name\" content=\"MAC\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-04T13:34:11+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/mac.colleccions.cat\/wp-content\/uploads\/MAC_ULL-03484-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"2066\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/mac.colleccions.cat\\\/en\\\/objecte\\\/mac-ull-03484\\\/\",\"url\":\"https:\\\/\\\/mac.colleccions.cat\\\/en\\\/objecte\\\/mac-ull-03484\\\/\",\"name\":\"aplic en forma de cap - MAC\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mac.colleccions.cat\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/mac.colleccions.cat\\\/en\\\/objecte\\\/mac-ull-03484\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/mac.colleccions.cat\\\/en\\\/objecte\\\/mac-ull-03484\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/mac.colleccions.cat\\\/wp-content\\\/uploads\\\/MAC_ULL-03484-scaled.jpg\",\"datePublished\":\"2021-09-30T20:52:43+00:00\",\"dateModified\":\"2025-12-04T13:34:11+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/mac.colleccions.cat\\\/en\\\/objecte\\\/mac-ull-03484\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/mac.colleccions.cat\\\/en\\\/objecte\\\/mac-ull-03484\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/mac.colleccions.cat\\\/en\\\/objecte\\\/mac-ull-03484\\\/#primaryimage\",\"url\":\"https:\\\/\\\/mac.colleccions.cat\\\/wp-content\\\/uploads\\\/MAC_ULL-03484-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/mac.colleccions.cat\\\/wp-content\\\/uploads\\\/MAC_ULL-03484-scaled.jpg\",\"width\":2560,\"height\":2066},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/mac.colleccions.cat\\\/en\\\/objecte\\\/mac-ull-03484\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inici\",\"item\":\"https:\\\/\\\/mac.colleccions.cat\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Objectes\",\"item\":\"https:\\\/\\\/mac.colleccions.cat\\\/objecte\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"aplic en forma de cap\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/mac.colleccions.cat\\\/#website\",\"url\":\"https:\\\/\\\/mac.colleccions.cat\\\/\",\"name\":\"MAC\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/mac.colleccions.cat\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/mac.colleccions.cat\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/mac.colleccions.cat\\\/#organization\",\"name\":\"MAC\",\"url\":\"https:\\\/\\\/mac.colleccions.cat\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/mac.colleccions.cat\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/mac.colleccions.cat\\\/wp-content\\\/uploads\\\/MAC-logo.svg\",\"contentUrl\":\"https:\\\/\\\/mac.colleccions.cat\\\/wp-content\\\/uploads\\\/MAC-logo.svg\",\"width\":349,\"height\":68,\"caption\":\"MAC\"},\"image\":{\"@id\":\"https:\\\/\\\/mac.colleccions.cat\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"aplic en forma de cap - MAC","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/mac.colleccions.cat\/en\/objecte\/mac-ull-03484\/","og_locale":"en_US","og_type":"article","og_title":"aplic en forma de cap - MAC","og_description":"[...]Read More... from aplic en forma de cap","og_url":"https:\/\/mac.colleccions.cat\/en\/objecte\/mac-ull-03484\/","og_site_name":"MAC","article_modified_time":"2025-12-04T13:34:11+00:00","og_image":[{"width":2560,"height":2066,"url":"https:\/\/mac.colleccions.cat\/wp-content\/uploads\/MAC_ULL-03484-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/mac.colleccions.cat\/en\/objecte\/mac-ull-03484\/","url":"https:\/\/mac.colleccions.cat\/en\/objecte\/mac-ull-03484\/","name":"aplic en forma de cap - MAC","isPartOf":{"@id":"https:\/\/mac.colleccions.cat\/#website"},"primaryImageOfPage":{"@id":"https:\/\/mac.colleccions.cat\/en\/objecte\/mac-ull-03484\/#primaryimage"},"image":{"@id":"https:\/\/mac.colleccions.cat\/en\/objecte\/mac-ull-03484\/#primaryimage"},"thumbnailUrl":"https:\/\/mac.colleccions.cat\/wp-content\/uploads\/MAC_ULL-03484-scaled.jpg","datePublished":"2021-09-30T20:52:43+00:00","dateModified":"2025-12-04T13:34:11+00:00","breadcrumb":{"@id":"https:\/\/mac.colleccions.cat\/en\/objecte\/mac-ull-03484\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/mac.colleccions.cat\/en\/objecte\/mac-ull-03484\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/mac.colleccions.cat\/en\/objecte\/mac-ull-03484\/#primaryimage","url":"https:\/\/mac.colleccions.cat\/wp-content\/uploads\/MAC_ULL-03484-scaled.jpg","contentUrl":"https:\/\/mac.colleccions.cat\/wp-content\/uploads\/MAC_ULL-03484-scaled.jpg","width":2560,"height":2066},{"@type":"BreadcrumbList","@id":"https:\/\/mac.colleccions.cat\/en\/objecte\/mac-ull-03484\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inici","item":"https:\/\/mac.colleccions.cat\/"},{"@type":"ListItem","position":2,"name":"Objectes","item":"https:\/\/mac.colleccions.cat\/objecte\/"},{"@type":"ListItem","position":3,"name":"aplic en forma de cap"}]},{"@type":"WebSite","@id":"https:\/\/mac.colleccions.cat\/#website","url":"https:\/\/mac.colleccions.cat\/","name":"MAC","description":"","publisher":{"@id":"https:\/\/mac.colleccions.cat\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mac.colleccions.cat\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/mac.colleccions.cat\/#organization","name":"MAC","url":"https:\/\/mac.colleccions.cat\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/mac.colleccions.cat\/#\/schema\/logo\/image\/","url":"https:\/\/mac.colleccions.cat\/wp-content\/uploads\/MAC-logo.svg","contentUrl":"https:\/\/mac.colleccions.cat\/wp-content\/uploads\/MAC-logo.svg","width":349,"height":68,"caption":"MAC"},"image":{"@id":"https:\/\/mac.colleccions.cat\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/mac.colleccions.cat\/en\/wp-json\/wp\/v2\/objecte\/9466","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mac.colleccions.cat\/en\/wp-json\/wp\/v2\/objecte"}],"about":[{"href":"https:\/\/mac.colleccions.cat\/en\/wp-json\/wp\/v2\/types\/objecte"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mac.colleccions.cat\/en\/wp-json\/wp\/v2\/media\/9452"}],"wp:attachment":[{"href":"https:\/\/mac.colleccions.cat\/en\/wp-json\/wp\/v2\/media?parent=9466"}],"wp:term":[{"taxonomy":"museu","embeddable":true,"href":"https:\/\/mac.colleccions.cat\/en\/wp-json\/wp\/v2\/museu?post=9466"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}